{"id":36828,"date":"2024-10-17T22:19:39","date_gmt":"2024-10-17T20:19:39","guid":{"rendered":"https:\/\/polymusiq.com\/courses\/flute-traversiere\/"},"modified":"2024-10-17T22:19:39","modified_gmt":"2024-10-17T20:19:39","slug":"flute-traversiere","status":"publish","type":"courses","link":"https:\/\/polymusiq.com\/de\/courses\/flute-traversiere\/","title":{"rendered":"Querfl\u00f6te"},"content":{"rendered":"<p>In meinem Unterricht geht es um verschiedene Aspekte, die f\u00fcr ein gutes Querfl\u00f6tenspiel und einen freien musikalischen Ausdruck notwendig sind: gesunde K\u00f6rperhaltung, stabile Technik, aufmerksames Zuh\u00f6ren, Musikalit\u00e4t, pers\u00f6nliche Entwicklung. Daraus ergeben sich die Klangqualit\u00e4t, die Finger- und Atemtechnik, die Intonation, der Ausdruck und vieles mehr. Ich lege auch Wert auf das Wohlbefinden, das Selbstvertrauen oder andere F\u00e4higkeiten, die der Sch\u00fcler oder die Sch\u00fclerin erwerben m\u00f6chte.<\/p>","protected":false},"author":93,"featured_media":36827,"template":"","course-place":[114],"class_list":["post-36828","courses","type-courses","status-publish","has-post-thumbnail","hentry","course-place-lausanne"],"_links":{"self":[{"href":"https:\/\/polymusiq.com\/de\/wp-json\/wp\/v2\/courses\/36828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/polymusiq.com\/de\/wp-json\/wp\/v2\/courses"}],"about":[{"href":"https:\/\/polymusiq.com\/de\/wp-json\/wp\/v2\/types\/courses"}],"author":[{"embeddable":true,"href":"https:\/\/polymusiq.com\/de\/wp-json\/wp\/v2\/users\/93"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/polymusiq.com\/de\/wp-json\/wp\/v2\/media\/36827"}],"wp:attachment":[{"href":"https:\/\/polymusiq.com\/de\/wp-json\/wp\/v2\/media?parent=36828"}],"wp:term":[{"taxonomy":"course-place","embeddable":true,"href":"https:\/\/polymusiq.com\/de\/wp-json\/wp\/v2\/course-place?post=36828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}